{"id":2803,"date":"2026-01-05T20:44:57","date_gmt":"2026-01-05T20:44:57","guid":{"rendered":"https:\/\/nen.kmkoncept.fr\/?post_type=product&#038;p=2803"},"modified":"2026-09-01T16:35:10","modified_gmt":"2026-09-01T16:35:10","slug":"taud-europe-dessous-coton-polyester","status":"publish","type":"product","link":"https:\/\/www.nenuphar.com\/en\/shop\/series\/deriveurs\/europe\/taud-europe-dessous-coton-polyester\/","title":{"rendered":"Europe Bottom Cover \u2013 Cotton\/Polyester"},"content":{"rendered":"<p>Made in France. Bottom cover for Europe \u2013 ELEGANCE range in acrylic\/polyester with exterior treatment. Covers the entire hull and extends over the tanks. Fastened with transverse straps fitted with clip buckles for quick and easy installatio<\/p>","protected":false},"excerpt":{"rendered":"<p><span style=\"text-decoration:underline;\">Marine acrylic<\/span>100% solution-dyed acrylic, offering exceptional color fastness. This fabric is not coated and retains a textile feel on both sides. It is breathable and quick-drying. Water resistance and rot-proof properties are ensured by a special marine treatment. Weight: 315 g\/m\u00b2. This fabric is made in France.<\/p>","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","_members_access_role":[],"_members_access_error":""},"product_brand":[430],"product_cat":[200,406],"product_tag":[483],"class_list":["post-2803","product","type-product","status-publish","product_brand-nenuphar","product_cat-europe","product_cat-taud-dessous-deriveurs","product_tag-europe","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"L\u2019acrylique marin: 100% acrylique, teint\u00e9 dans la masse, ce qui donne une r\u00e9sistance des coloris imbattable. Cette toile n\u2019est pas enduite et garde un aspect tissu sur ses 2 faces. Elle est respirante et s\u00e8che vite. L\u2019imperm\u00e9abilit\u00e9 \u00e0 l\u2019eau et l\u2019imputrescibilit\u00e9 sont assur\u00e9es par un traitement sp\u00e9cial marine. Le grammage est de 315 g\/m\u00b2. Ce tissu est fabriqu\u00e9 en France.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.nenuphar.com\/en\/shop\/series\/deriveurs\/europe\/taud-europe-dessous-coton-polyester\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_GB\" \/>\n\t\t<meta property=\"og:site_name\" content=\"NENUPHAR - Votre \u00e9quipementier voile l\u00e9g\u00e8re\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"TAUD EUROPE DESSOUS COTON \u2013 POLYESTER - NENUPHAR\" \/>\n\t\t<meta property=\"og:description\" content=\"L\u2019acrylique marin: 100% acrylique, teint\u00e9 dans la masse, ce qui donne une r\u00e9sistance des coloris imbattable. Cette toile n\u2019est pas enduite et garde un aspect tissu sur ses 2 faces. Elle est respirante et s\u00e8che vite. L\u2019imperm\u00e9abilit\u00e9 \u00e0 l\u2019eau et l\u2019imputrescibilit\u00e9 sont assur\u00e9es par un traitement sp\u00e9cial marine. Le grammage est de 315 g\/m\u00b2. Ce tissu est fabriqu\u00e9 en France.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.nenuphar.com\/en\/shop\/series\/deriveurs\/europe\/taud-europe-dessous-coton-polyester\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.nenuphar.com\/wp-content\/uploads\/2025\/12\/cropped-cropped-cropped-cropped-logo-1-1.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.nenuphar.com\/wp-content\/uploads\/2025\/12\/cropped-cropped-cropped-cropped-logo-1-1.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-01-05T20:44:57+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-09-01T16:35:10+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"TAUD EUROPE DESSOUS COTON \u2013 POLYESTER - NENUPHAR\" \/>\n\t\t<meta name=\"twitter:description\" content=\"L\u2019acrylique marin: 100% acrylique, teint\u00e9 dans la masse, ce qui donne une r\u00e9sistance des coloris imbattable. Cette toile n\u2019est pas enduite et garde un aspect tissu sur ses 2 faces. Elle est respirante et s\u00e8che vite. L\u2019imperm\u00e9abilit\u00e9 \u00e0 l\u2019eau et l\u2019imputrescibilit\u00e9 sont assur\u00e9es par un traitement sp\u00e9cial marine. Le grammage est de 315 g\/m\u00b2. Ce tissu est fabriqu\u00e9 en France.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.nenuphar.com\/wp-content\/uploads\/2025\/12\/cropped-cropped-cropped-cropped-logo-1-1.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nenuphar.com\\\/en\\\/shop\\\/series\\\/deriveurs\\\/europe\\\/taud-europe-dessous-coton-polyester\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.nenuphar.com\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.nenuphar.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.nenuphar.com\\\/boutique\\\/#listItem\",\"name\":\"Boutique\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.nenuphar.com\\\/boutique\\\/#listItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/www.nenuphar.com\\\/boutique\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.nenuphar.com\\\/en\\\/brand\\\/nenuphar\\\/#listItem\",\"name\":\"Nenuphar\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.nenuphar.com\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.nenuphar.com\\\/en\\\/brand\\\/nenuphar\\\/#listItem\",\"position\":3,\"name\":\"Nenuphar\",\"item\":\"https:\\\/\\\/www.nenuphar.com\\\/en\\\/brand\\\/nenuphar\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.nenuphar.com\\\/en\\\/shop\\\/series\\\/deriveurs\\\/europe\\\/taud-europe-dessous-coton-polyester\\\/#listItem\",\"name\":\"TAUD EUROPE DESSOUS COTON &#8211; POLYESTER\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.nenuphar.com\\\/boutique\\\/#listItem\",\"name\":\"Boutique\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.nenuphar.com\\\/en\\\/shop\\\/series\\\/deriveurs\\\/europe\\\/taud-europe-dessous-coton-polyester\\\/#listItem\",\"position\":4,\"name\":\"TAUD EUROPE DESSOUS COTON &#8211; POLYESTER\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.nenuphar.com\\\/en\\\/brand\\\/nenuphar\\\/#listItem\",\"name\":\"Nenuphar\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/www.nenuphar.com\\\/en\\\/shop\\\/series\\\/deriveurs\\\/europe\\\/taud-europe-dessous-coton-polyester\\\/#itempage\",\"url\":\"https:\\\/\\\/www.nenuphar.com\\\/en\\\/shop\\\/series\\\/deriveurs\\\/europe\\\/taud-europe-dessous-coton-polyester\\\/\",\"name\":\"TAUD EUROPE DESSOUS COTON \\u2013 POLYESTER - NENUPHAR\",\"description\":\"L\\u2019acrylique marin: 100% acrylique, teint\\u00e9 dans la masse, ce qui donne une r\\u00e9sistance des coloris imbattable. Cette toile n\\u2019est pas enduite et garde un aspect tissu sur ses 2 faces. Elle est respirante et s\\u00e8che vite. L\\u2019imperm\\u00e9abilit\\u00e9 \\u00e0 l\\u2019eau et l\\u2019imputrescibilit\\u00e9 sont assur\\u00e9es par un traitement sp\\u00e9cial marine. Le grammage est de 315 g\\\/m\\u00b2. Ce tissu est fabriqu\\u00e9 en France.\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nenuphar.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nenuphar.com\\\/en\\\/shop\\\/series\\\/deriveurs\\\/europe\\\/taud-europe-dessous-coton-polyester\\\/#breadcrumblist\"},\"datePublished\":\"2026-01-05T20:44:57+00:00\",\"dateModified\":\"2026-09-01T16:35:10+00:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.nenuphar.com\\\/en\\\/#organization\",\"name\":\"NENUPHAR\",\"description\":\"Sp\\u00e9cialiste des d\\u00e9riveurs Laser et Open BIC, planches \\u00e0 voile, paddles, S.U.P., voilerie, accastillage, m\\u00e2ts et entretien voile l\\u00e9g\\u00e8re pour clubs de voile.\",\"url\":\"https:\\\/\\\/www.nenuphar.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.nenuphar.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/cropped-cropped-cropped-cropped-logo-1-1.png\",\"@id\":\"https:\\\/\\\/www.nenuphar.com\\\/en\\\/shop\\\/series\\\/deriveurs\\\/europe\\\/taud-europe-dessous-coton-polyester\\\/#organizationLogo\",\"width\":966,\"height\":359},\"image\":{\"@id\":\"https:\\\/\\\/www.nenuphar.com\\\/en\\\/shop\\\/series\\\/deriveurs\\\/europe\\\/taud-europe-dessous-coton-polyester\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nenuphar.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.nenuphar.com\\\/en\\\/\",\"name\":\"NENUPHAR\",\"description\":\"Votre \\u00e9quipementier voile l\\u00e9g\\u00e8re\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.nenuphar.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"TAUD EUROPE DESSOUS COTON \u2013 POLYESTER - NENUPHAR","description":"L\u2019acrylique marin: 100% acrylique, teint\u00e9 dans la masse, ce qui donne une r\u00e9sistance des coloris imbattable. Cette toile n\u2019est pas enduite et garde un aspect tissu sur ses 2 faces. Elle est respirante et s\u00e8che vite. L\u2019imperm\u00e9abilit\u00e9 \u00e0 l\u2019eau et l\u2019imputrescibilit\u00e9 sont assur\u00e9es par un traitement sp\u00e9cial marine. Le grammage est de 315 g\/m\u00b2. Ce tissu est fabriqu\u00e9 en France.","canonical_url":"https:\/\/www.nenuphar.com\/en\/shop\/series\/deriveurs\/europe\/taud-europe-dessous-coton-polyester\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.nenuphar.com\/en\/shop\/series\/deriveurs\/europe\/taud-europe-dessous-coton-polyester\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.nenuphar.com\/en#listItem","position":1,"name":"Home","item":"https:\/\/www.nenuphar.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/www.nenuphar.com\/boutique\/#listItem","name":"Boutique"}},{"@type":"ListItem","@id":"https:\/\/www.nenuphar.com\/boutique\/#listItem","position":2,"name":"Boutique","item":"https:\/\/www.nenuphar.com\/boutique\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.nenuphar.com\/en\/brand\/nenuphar\/#listItem","name":"Nenuphar"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.nenuphar.com\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.nenuphar.com\/en\/brand\/nenuphar\/#listItem","position":3,"name":"Nenuphar","item":"https:\/\/www.nenuphar.com\/en\/brand\/nenuphar\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.nenuphar.com\/en\/shop\/series\/deriveurs\/europe\/taud-europe-dessous-coton-polyester\/#listItem","name":"TAUD EUROPE DESSOUS COTON &#8211; POLYESTER"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.nenuphar.com\/boutique\/#listItem","name":"Boutique"}},{"@type":"ListItem","@id":"https:\/\/www.nenuphar.com\/en\/shop\/series\/deriveurs\/europe\/taud-europe-dessous-coton-polyester\/#listItem","position":4,"name":"TAUD EUROPE DESSOUS COTON &#8211; POLYESTER","previousItem":{"@type":"ListItem","@id":"https:\/\/www.nenuphar.com\/en\/brand\/nenuphar\/#listItem","name":"Nenuphar"}}]},{"@type":"ItemPage","@id":"https:\/\/www.nenuphar.com\/en\/shop\/series\/deriveurs\/europe\/taud-europe-dessous-coton-polyester\/#itempage","url":"https:\/\/www.nenuphar.com\/en\/shop\/series\/deriveurs\/europe\/taud-europe-dessous-coton-polyester\/","name":"TAUD EUROPE DESSOUS COTON \u2013 POLYESTER - NENUPHAR","description":"L\u2019acrylique marin: 100% acrylique, teint\u00e9 dans la masse, ce qui donne une r\u00e9sistance des coloris imbattable. Cette toile n\u2019est pas enduite et garde un aspect tissu sur ses 2 faces. Elle est respirante et s\u00e8che vite. L\u2019imperm\u00e9abilit\u00e9 \u00e0 l\u2019eau et l\u2019imputrescibilit\u00e9 sont assur\u00e9es par un traitement sp\u00e9cial marine. Le grammage est de 315 g\/m\u00b2. Ce tissu est fabriqu\u00e9 en France.","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/www.nenuphar.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.nenuphar.com\/en\/shop\/series\/deriveurs\/europe\/taud-europe-dessous-coton-polyester\/#breadcrumblist"},"datePublished":"2026-01-05T20:44:57+00:00","dateModified":"2026-09-01T16:35:10+00:00"},{"@type":"Organization","@id":"https:\/\/www.nenuphar.com\/en\/#organization","name":"NENUPHAR","description":"Sp\u00e9cialiste des d\u00e9riveurs Laser et Open BIC, planches \u00e0 voile, paddles, S.U.P., voilerie, accastillage, m\u00e2ts et entretien voile l\u00e9g\u00e8re pour clubs de voile.","url":"https:\/\/www.nenuphar.com\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/www.nenuphar.com\/wp-content\/uploads\/2025\/12\/cropped-cropped-cropped-cropped-logo-1-1.png","@id":"https:\/\/www.nenuphar.com\/en\/shop\/series\/deriveurs\/europe\/taud-europe-dessous-coton-polyester\/#organizationLogo","width":966,"height":359},"image":{"@id":"https:\/\/www.nenuphar.com\/en\/shop\/series\/deriveurs\/europe\/taud-europe-dessous-coton-polyester\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/www.nenuphar.com\/en\/#website","url":"https:\/\/www.nenuphar.com\/en\/","name":"NENUPHAR","description":"Votre \u00e9quipementier voile l\u00e9g\u00e8re","inLanguage":"en-GB","publisher":{"@id":"https:\/\/www.nenuphar.com\/en\/#organization"}}]},"og:locale":"en_GB","og:site_name":"NENUPHAR - Votre \u00e9quipementier voile l\u00e9g\u00e8re","og:type":"article","og:title":"TAUD EUROPE DESSOUS COTON \u2013 POLYESTER - NENUPHAR","og:description":"L\u2019acrylique marin: 100% acrylique, teint\u00e9 dans la masse, ce qui donne une r\u00e9sistance des coloris imbattable. Cette toile n\u2019est pas enduite et garde un aspect tissu sur ses 2 faces. Elle est respirante et s\u00e8che vite. L\u2019imperm\u00e9abilit\u00e9 \u00e0 l\u2019eau et l\u2019imputrescibilit\u00e9 sont assur\u00e9es par un traitement sp\u00e9cial marine. Le grammage est de 315 g\/m\u00b2. Ce tissu est fabriqu\u00e9 en France.","og:url":"https:\/\/www.nenuphar.com\/en\/shop\/series\/deriveurs\/europe\/taud-europe-dessous-coton-polyester\/","og:image":"https:\/\/www.nenuphar.com\/wp-content\/uploads\/2025\/12\/cropped-cropped-cropped-cropped-logo-1-1.png","og:image:secure_url":"https:\/\/www.nenuphar.com\/wp-content\/uploads\/2025\/12\/cropped-cropped-cropped-cropped-logo-1-1.png","article:published_time":"2026-01-05T20:44:57+00:00","article:modified_time":"2026-09-01T16:35:10+00:00","twitter:card":"summary_large_image","twitter:title":"TAUD EUROPE DESSOUS COTON \u2013 POLYESTER - NENUPHAR","twitter:description":"L\u2019acrylique marin: 100% acrylique, teint\u00e9 dans la masse, ce qui donne une r\u00e9sistance des coloris imbattable. Cette toile n\u2019est pas enduite et garde un aspect tissu sur ses 2 faces. Elle est respirante et s\u00e8che vite. L\u2019imperm\u00e9abilit\u00e9 \u00e0 l\u2019eau et l\u2019imputrescibilit\u00e9 sont assur\u00e9es par un traitement sp\u00e9cial marine. Le grammage est de 315 g\/m\u00b2. Ce tissu est fabriqu\u00e9 en France.","twitter:image":"https:\/\/www.nenuphar.com\/wp-content\/uploads\/2025\/12\/cropped-cropped-cropped-cropped-logo-1-1.png"},"aioseo_meta_data":{"post_id":"2803","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2026-01-06 07:49:51","updated":"2026-08-14 10:33:23","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.nenuphar.com\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.nenuphar.com\/boutique\/\" title=\"Boutique\">Boutique<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.nenuphar.com\/en\/brand\/nenuphar\/\" title=\"Nenuphar\">Nenuphar<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tTAUD EUROPE DESSOUS COTON \u2013 POLYESTER\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.nenuphar.com\/en"},{"label":"Boutique","link":"https:\/\/www.nenuphar.com\/boutique\/"},{"label":"Nenuphar","link":"https:\/\/www.nenuphar.com\/en\/brand\/nenuphar\/"},{"label":"TAUD EUROPE DESSOUS COTON &#8211; POLYESTER","link":"https:\/\/www.nenuphar.com\/en\/shop\/series\/deriveurs\/europe\/taud-europe-dessous-coton-polyester\/"}],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false,"woocommerce_thumbnail":false,"woocommerce_single":false,"woocommerce_gallery_thumbnail":false},"uagb_author_info":{"display_name":"Karine","author_link":"https:\/\/www.nenuphar.com\/en\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"L\u2019acrylique marin: 100% acrylique, teint\u00e9 dans la masse, ce qui donne une r\u00e9sistance des coloris imbattable. Cette toile n\u2019est pas enduite et garde un aspect tissu sur ses 2 faces. Elle est respirante et s\u00e8che vite. L\u2019imperm\u00e9abilit\u00e9 \u00e0 l\u2019eau et l\u2019imputrescibilit\u00e9 sont assur\u00e9es par un traitement sp\u00e9cial marine. Le grammage est de 315 g\/m\u00b2. Ce&hellip;","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.nenuphar.com\/en\/wp-json\/wp\/v2\/product\/2803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nenuphar.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.nenuphar.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/www.nenuphar.com\/en\/wp-json\/wp\/v2\/media?parent=2803"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.nenuphar.com\/en\/wp-json\/wp\/v2\/product_brand?post=2803"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.nenuphar.com\/en\/wp-json\/wp\/v2\/product_cat?post=2803"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.nenuphar.com\/en\/wp-json\/wp\/v2\/product_tag?post=2803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}